{"id":546,"date":"2019-12-09T16:02:30","date_gmt":"2019-12-09T15:02:30","guid":{"rendered":"http:\/\/pugliasapori.creamstudio.it\/tarallini-evo-linea-classica\/"},"modified":"2026-01-30T17:44:19","modified_gmt":"2026-01-30T16:44:19","slug":"extra-virgin-olive-oil-tarallini-classic-line","status":"publish","type":"page","link":"https:\/\/pugliasapori.com\/en\/extra-virgin-olive-oil-tarallini-classic-line\/","title":{"rendered":"EXTRA VIRGIN OLIVE OIL TARALLINI"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EXTRA VIRGIN OLIVE OIL TARALLINI - Puglia Sapori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pugliasapori.com\/en\/extra-virgin-olive-oil-tarallini-classic-line\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXTRA VIRGIN OLIVE OIL TARALLINI - Puglia Sapori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pugliasapori.com\/en\/extra-virgin-olive-oil-tarallini-classic-line\/\" \/>\n<meta property=\"og:site_name\" content=\"Puglia Sapori\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T16:44:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"admin-pugliasapori\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pugliasapori.com\/#website\",\"url\":\"https:\/\/pugliasapori.com\/\",\"name\":\"Puglia Sapori\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/pugliasapori.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pugliasapori.com\/en\/extra-virgin-olive-oil-tarallini-classic-line\/#webpage\",\"url\":\"https:\/\/pugliasapori.com\/en\/extra-virgin-olive-oil-tarallini-classic-line\/\",\"name\":\"EXTRA VIRGIN OLIVE OIL TARALLINI - Puglia Sapori\",\"isPartOf\":{\"@id\":\"https:\/\/pugliasapori.com\/#website\"},\"datePublished\":\"2019-12-09T15:02:30+00:00\",\"dateModified\":\"2026-01-30T16:44:19+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pugliasapori.com\/en\/extra-virgin-olive-oil-tarallini-classic-line\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/pages\/546"}],"collection":[{"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/comments?post=546"}],"version-history":[{"count":2,"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/pages\/546\/revisions"}],"predecessor-version":[{"id":548,"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/pages\/546\/revisions\/548"}],"wp:attachment":[{"href":"https:\/\/pugliasapori.com\/en\/wp-json\/wp\/v2\/media?parent=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}